{"id":76,"date":"2021-02-02T17:34:44","date_gmt":"2021-02-02T10:34:44","guid":{"rendered":"https:\/\/www.yangkrok.com\/home\/?page_id=76"},"modified":"2022-09-01T20:06:17","modified_gmt":"2022-09-01T13:06:17","slug":"ita-online-2020","status":"publish","type":"page","link":"https:\/\/www.yangkrok.com\/home\/ita-online-2020\/","title":{"rendered":"ITA Online 2020"},"content":{"rendered":"\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\">OIT \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e22\u0e32\u0e07\u0e04\u0e23\u0e01<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1021\" height=\"265\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2021\/02\/header-27x7-2020.png\" alt=\"\" class=\"wp-image-275\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2021\/02\/header-27x7-2020.png 1021w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2021\/02\/header-27x7-2020-300x78.png 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2021\/02\/header-27x7-2020-768x199.png 768w\" sizes=\"auto, (max-width: 1021px) 100vw, 1021px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u0e41\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 (Open Data Integrity and Transparency Assessment: OIT) \u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e48\u0e2d\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e44\u0e14\u0e49 \u0e43\u0e19\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e18\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e42\u0e1b\u0e23\u0e48\u0e07\u0e43\u0e2a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 (ITA) \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e1e.\u0e28.2563 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e22\u0e32\u0e07\u0e04\u0e23\u0e01 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 5<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e17\u0e35\u0e48 9 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">. : : \u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e22\u0e48\u0e2d\u0e22\u0e17\u0e35\u0e48 9.1 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19<br>O1 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1jp5HX_HN8VVqIcPcm6CBLKqy9-hO0arN\/view?usp=sharing\" target=\"_blank\">\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07<\/a> <br>O2 : <a rel=\"noreferrer noopener\" href=\"https:\/\/www.yangkrok.com\/home\/director\/\" target=\"_blank\">\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/a><br>O3 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/17hpeKzgaN7H8U5ua-4kY3BzVGrvKrQJQ\/view\" target=\"_blank\">\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48<\/a> <br>O4 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1_PvN2dXTLmdxW92oO_1BQZnR2fffhj14\/view?usp=sharing\" target=\"_blank\">\u0e41\u0e1c\u0e19\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e2b\u0e23\u0e37\u0e2d \u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19<\/a> <br>O5 : <a rel=\"noreferrer noopener\" href=\"https:\/\/www.yangkrok.com\/home\/contact\/\" target=\"_blank\">\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d<\/a> <br>O6 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/drive\/folders\/1JWxgBh2y_RJ4fgLcT8DOONSwo1UU0Ri4?usp=sharing\" target=\"_blank\">\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/a> <br>O7 : <a rel=\"noreferrer noopener\" href=\"https:\/\/www.yangkrok.com\/home\/\" target=\"_blank\">\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a> <br>O8 : <a rel=\"noreferrer noopener\" href=\"https:\/\/www.yangkrok.com\/home\/questions\/\" target=\"_blank\">\u0e01\u0e23\u0e30\u0e14\u0e32\u0e19\u0e16\u0e32\u0e21-\u0e15\u0e2d\u0e1a<\/a> <br>O9 : <a href=\"https:\/\/www.yangkrok.com\/home\/social-media\/\" target=\"_blank\" rel=\"noreferrer noopener\">Social Network<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">. : : \u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e22\u0e48\u0e2d\u0e22\u0e17\u0e35\u0e48 9.2 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19<br>O10 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1Mu2tkttoR1hffXt4rx630XLlI9DuRKOK\/view?usp=sharing\" target=\"_blank\">\u0e41\u0e1c\u0e19\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2563<\/a> <br>O11 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1ieKwNOK5PetEiLTM6WzdSvlNz0OjnNq8\/view?usp=sharing\" target=\"_blank\">\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e01\u0e33\u0e01\u0e31\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e23\u0e2d\u0e1a 6 \u0e40\u0e14\u0e37\u0e2d\u0e19<\/a><br>O12 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1AUcRzFnwAuq7A3Ix-2EMO0YT1gan6U3q\/view?usp=sharing\" target=\"_blank\">\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2562<\/a> <br>O13 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/drive\/folders\/16OEn3e1c5U52VmWynd0CyI4uKQ_guLp8?usp=sharing\" target=\"_blank\">\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19<\/a> <br>O14 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/15_BS9NzvZ43zYKX2DmAJKjtC4SF0o1jp\/view?usp=sharing\" target=\"_blank\">\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 <\/a><br>O15 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1UID3vcuejiM5a2GwuOx-JrnukrsVJnuB\/view?usp=sharing\" target=\"_blank\">\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e0a\u0e34\u0e07\u0e2a\u0e16\u0e34\u0e15\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/a>  <br>O16 : <a href=\"https:\/\/drive.google.com\/file\/d\/15dQ7wYwUi4-8fwRJJSTcmGBsUw5glbmQ\/view?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e36\u0e07\u0e1e\u0e2d\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/a><br>O17 : <a rel=\"noreferrer noopener\" href=\"https:\/\/www.yangkrok.com\/home\/e-service\/\" target=\"_blank\">E-Service<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">. : : \u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e22\u0e48\u0e2d\u0e22\u0e17\u0e35\u0e48 9.3 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 <br>O18 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1iGIQbbQhu8Swl8wqGszfomMi6KGmcHm_\/view?usp=sharing\" target=\"_blank\">\u0e41\u0e1c\u0e19<\/a><a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1iGIQbbQhu8Swl8wqGszfomMi6KGmcHm_\/view\" target=\"_blank\">\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35<\/a> <br>O19 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1nC9Imb2z6MEMoFvq4iASTqf6AG1sdxBL\/view?usp=sharing\" target=\"_blank\">\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e23\u0e2d\u0e1a 6 \u0e40\u0e14\u0e37\u0e2d\u0e19<\/a> <br>O20 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1zgq25cxNV0TwRGJTpVIOMvQkpHIsai1x\/view?usp=sharing\" target=\"_blank\">\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 <\/a><br>O21 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1NCNy2H9kdeZWJxDRKlm6faQUNJKbYDID\/view?usp=sharing\" target=\"_blank\">\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1e\u0e31\u0e2a\u0e14\u0e38<\/a> <br>O22 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1UpneBL6F_nBSTAEO29bEi1ORhLwvjQeL\/view?usp=sharing\" target=\"_blank\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1e\u0e31\u0e2a\u0e14\u0e38<\/a> <br>O23 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1kglXBezz3q00EsMcjJwv_ndzlvXvL6Gs\/view?usp=sharing\" target=\"_blank\">\u0e2a\u0e23\u0e38\u0e1b\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19<\/a> <br>O24 : <a href=\"https:\/\/drive.google.com\/file\/d\/1bU2K4aPQqMXcs9yTPLpYoHuEKhseAQnA\/view?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">. : :&nbsp;\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e22\u0e48\u0e2d\u0e22\u0e17\u0e35\u0e48 9.4 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25<br>O25 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1d4JIsp7rPAWhLKv7PdgKmbOA_FCqeqG2\/view?usp=sharing\" target=\"_blank\">\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25<\/a> <br>O26 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1HQ5fDQC3smj5h7w3pLCkAq1_4oH59gbF\/view?usp=sharing\" target=\"_blank\">\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25<\/a><br>O27 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1Tw7hkN3aOUfTiWOdvDfRWCwCCGxQWqxS\/view?usp=sharing\" target=\"_blank\">\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25<\/a><br>O28 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/19z56YgBowmxg0Yij68dhmlb8mGabc-sd\/view?usp=sharing\" target=\"_blank\">\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">. : :&nbsp;\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e22\u0e48\u0e2d\u0e22\u0e17\u0e35\u0e48 9.5 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e42\u0e1b\u0e23\u0e48\u0e07\u0e43\u0e2a<br>O29 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1CHqTfWRt4Lv7fjqX1JNwBh9mNtePPQYH\/view?usp=sharing\" target=\"_blank\">\u0e41\u0e19\u0e27\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e1e\u0e24\u0e15\u0e34\u0e21\u0e34\u0e0a\u0e2d\u0e1a<\/a> <br>O30 : <a rel=\"noreferrer noopener\" href=\"https:\/\/www.yangkrok.com\/home\/complaint\/\" target=\"_blank\">\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e1e\u0e24\u0e15\u0e34\u0e21\u0e34\u0e0a\u0e2d\u0e1a<\/a> <br>O31 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1MAr40Vlce3ALHmB99TOBvbG9bysUf9w5\/view?usp=sharing\" target=\"_blank\">\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e0a\u0e34\u0e07\u0e2a\u0e16\u0e34\u0e15\u0e34\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e1e\u0e24\u0e15\u0e34\u0e21\u0e34\u0e0a\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35<\/a> <br>O32 : <a href=\"https:\/\/www.yangkrok.com\/home\/listen-to-opinions\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19<\/a><br>O33 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1OgKTskZyVZO8dKEthZboAwfIFnLhw9oS\/view?usp=sharing\" target=\"_blank\">\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21 <\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e17\u0e35\u0e48 10 \u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15<br>&nbsp;. : :&nbsp;\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e22\u0e48\u0e2d\u0e22\u0e17\u0e35\u0e48 10.1 \u0e40\u0e08\u0e15\u0e08\u0e33\u0e19\u0e07\u0e2a\u0e38\u0e08\u0e23\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<br>O34 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1ODqYURtRKGe_uI_KH7r2EGotL9FJEqXo\/view?usp=sharing\" target=\"_blank\">\u0e40\u0e08\u0e15\u0e08\u0e33\u0e19\u0e07\u0e2a\u0e38\u0e08\u0e23\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/a> <br>O35 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1tqvmGUWdtul7h4ugP9K8Rc9nmMsHUxo9\/view?usp=sharing\" target=\"_blank\">\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 <\/a><br>O36 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1IoW3OViHowOhTxn8tzaO_a6GdGLG9xzB\/view?usp=sharing\" target=\"_blank\">\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e01\u0e32\u0e23\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35<\/a><br>O37 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/18Sxp1PNLsw2HLK7xqT4xFabByKevsSmW\/view?usp=sharing\" target=\"_blank\">\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e01\u0e32\u0e23\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15<\/a><br>O38 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1jpgmFc3N62-9aBIsaB-L5-b--G-4p-Eq\/view?usp=sharing\" target=\"_blank\">\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23<\/a><br>O39 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1SRLe1H0kL44iqtNp-616rBTqoo8rfK0r\/view?usp=sharing\" target=\"_blank\">\u0e41\u0e1c\u0e19\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35<\/a> <br>O40 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1hayrOhTKE8c9-xS0togOykYqfO3swQLk\/view?usp=sharing\" target=\"_blank\">\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15 \u0e23\u0e2d\u0e1a 6 \u0e40\u0e14\u0e37\u0e2d\u0e19 <\/a><br>O41 : <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/file\/d\/1lqwvR2-oMjs_RK9cD58GGtZs1VySCkkl\/view?usp=sharing\" target=\"_blank\">\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;. : :&nbsp;\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e22\u0e48\u0e2d\u0e22\u0e17\u0e35\u0e48 10.2 \u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15<br>O42 : \u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e38\u0e13\u0e18\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e42\u0e1b\u0e23\u0e48\u0e07\u0e43\u0e2a\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 <strong>[-]<\/strong><br>O43 : \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e38\u0e13\u0e18\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e42\u0e1b\u0e23\u0e48\u0e07\u0e43\u0e2a\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 <strong>[-]<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>OIT \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e22\u0e32\u0e07\u0e04\u0e23\u0e01 \u0e41\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 (Open Data Integrity and Transparency Assessment: OIT) \u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e48\u0e2d\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e44\u0e14\u0e49 \u0e43\u0e19\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e18\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e42\u0e1b\u0e23\u0e48\u0e07\u0e43\u0e2a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 (ITA) \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e1e.\u0e28.2563 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e22\u0e32\u0e07\u0e04\u0e23\u0e01 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 5 \u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e17\u0e35\u0e48 9 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 . : : \u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e22\u0e48\u0e2d\u0e22\u0e17\u0e35\u0e48 9.1 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19O1 : \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 O2 : \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23O3 : \u0e2d\u0e33\u0e19\u0e32\u0e08\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 O4 : \u0e41\u0e1c\u0e19\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e2b\u0e23\u0e37\u0e2d \u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 O5 : \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d O6 : \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 O7 : \u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c O8 : \u0e01\u0e23\u0e30\u0e14\u0e32\u0e19\u0e16\u0e32\u0e21-\u0e15\u0e2d\u0e1a O9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-76","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/pages\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/comments?post=76"}],"version-history":[{"count":89,"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/pages\/76\/revisions"}],"predecessor-version":[{"id":463,"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/pages\/76\/revisions\/463"}],"wp:attachment":[{"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/media?parent=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}