{"id":1190,"date":"2024-07-26T12:20:42","date_gmt":"2024-07-26T05:20:42","guid":{"rendered":"https:\/\/www.yangkrok.com\/home\/?p=1190"},"modified":"2024-07-26T12:28:38","modified_gmt":"2024-07-26T05:28:38","slug":"%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b9%84%e0%b8%97%e0%b8%a2","status":"publish","type":"post","link":"https:\/\/www.yangkrok.com\/home\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b9%84%e0%b8%97%e0%b8%a2\/","title":{"rendered":"\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39\u0e48\u0e04\u0e23\u0e39\u0e01\u0e25\u0e2d\u0e19\u0e2a\u0e38\u0e19\u0e17\u0e23\u0e20\u0e39\u0e48 \u0e2a\u0e39\u0e48\u0e27\u0e31\u0e19\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22"},"content":{"rendered":"\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/LINE_ALBUM_67-07-19-\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e2267_\u0e52\u0e54\u0e50\u0e57\u0e51\u0e59_23-1024x577.jpg\" alt=\"\" class=\"wp-image-1191 size-full\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/LINE_ALBUM_67-07-19-\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e2267_\u0e52\u0e54\u0e50\u0e57\u0e51\u0e59_23-1024x577.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/LINE_ALBUM_67-07-19-\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e2267_\u0e52\u0e54\u0e50\u0e57\u0e51\u0e59_23-300x169.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/LINE_ALBUM_67-07-19-\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e2267_\u0e52\u0e54\u0e50\u0e57\u0e51\u0e59_23-768x433.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/LINE_ALBUM_67-07-19-\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e2267_\u0e52\u0e54\u0e50\u0e57\u0e51\u0e59_23.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">19 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2567 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e22\u0e32\u0e07\u0e04\u0e23\u0e01 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e25\u0e38\u0e01\u0e08\u0e34\u0e15\u0e2a\u0e33\u0e19\u0e36\u0e01\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e23\u0e30\u0e2b\u0e19\u0e31\u0e01\u0e16\u0e36\u0e07\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e04\u0e39\u0e48\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e17\u0e22 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e38\u0e19\u0e17\u0e23\u0e20\u0e39\u0e48 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2a\u0e35 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e27\u0e32\u0e14\u0e20\u0e32\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2a\u0e35 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e14\u0e04\u0e31\u0e14\u0e25\u0e32\u0e22\u0e21\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e20\u0e32\u0e1e\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e01\u0e25\u0e2d\u0e19 8 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e43\u0e19\u0e27\u0e23\u0e23\u0e13\u0e04\u0e14\u0e35\u0e44\u0e17\u0e22 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e43\u0e19\u0e27\u0e23\u0e23\u0e13\u0e04\u0e14\u0e35\u0e44\u0e17\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e0a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e08\u0e32\u0e01\u0e04\u0e13\u0e30\u0e04\u0e23\u0e39\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e22\u0e32\u0e07\u0e04\u0e23\u0e01 \u0e13 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e22\u0e32\u0e07\u0e04\u0e23\u0e01 \u0e15\u0e33\u0e1a\u0e25\u0e22\u0e32\u0e07\u0e40\u0e1b\u0e35\u0e22\u0e07 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2d\u0e21\u0e01\u0e4b\u0e2d\u0e22 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48<\/p>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1193\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0287-1024x682.jpg\" alt=\"\" class=\"wp-image-1193\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0287-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0287-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0287-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0287.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1195\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0273-1024x682.jpg\" alt=\"\" class=\"wp-image-1195\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0273-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0273-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0273-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0273.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1194\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0274-1024x682.jpg\" alt=\"\" class=\"wp-image-1194\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0274-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0274-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0274-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0274.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1197\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0292-1024x682.jpg\" alt=\"\" class=\"wp-image-1197\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0292-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0292-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0292-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0292.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1196\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0293-1024x682.jpg\" alt=\"\" class=\"wp-image-1196\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0293-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0293-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0293-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0293.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1198\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0299-1024x682.jpg\" alt=\"\" class=\"wp-image-1198\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0299-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0299-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0299-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0299.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1201\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0341-1024x682.jpg\" alt=\"\" class=\"wp-image-1201\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0341-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0341-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0341-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0341.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1199\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0331-1024x682.jpg\" alt=\"\" class=\"wp-image-1199\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0331-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0331-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0331-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0331.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1200\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0336-1024x682.jpg\" alt=\"\" class=\"wp-image-1200\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0336-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0336-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0336-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0336.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1204\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0365-1024x682.jpg\" alt=\"\" class=\"wp-image-1204\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0365-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0365-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0365-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0365.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1202\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0355-1024x682.jpg\" alt=\"\" class=\"wp-image-1202\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0355-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0355-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0355-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0355.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1203\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0358-1024x682.jpg\" alt=\"\" class=\"wp-image-1203\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0358-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0358-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0358-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0358.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1207\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0476-1024x682.jpg\" alt=\"\" class=\"wp-image-1207\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0476-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0476-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0476-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0476.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1205\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0484-1024x682.jpg\" alt=\"\" class=\"wp-image-1205\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0484-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0484-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0484-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0484.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1206\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0494-1024x682.jpg\" alt=\"\" class=\"wp-image-1206\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0494-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0494-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0494-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0494.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1210\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0585-1024x682.jpg\" alt=\"\" class=\"wp-image-1210\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0585-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0585-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0585-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0585.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1209\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0591-1024x682.jpg\" alt=\"\" class=\"wp-image-1209\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0591-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0591-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0591-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0591.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1208\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0603-1024x682.jpg\" alt=\"\" class=\"wp-image-1208\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0603-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0603-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0603-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0603.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1213\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0839-1024x682.jpg\" alt=\"\" class=\"wp-image-1213\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0839-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0839-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0839-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0839.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1211\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0790-1024x682.jpg\" alt=\"\" class=\"wp-image-1211\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0790-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0790-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0790-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0790.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1212\" src=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0783-1024x682.jpg\" alt=\"\" class=\"wp-image-1212\" srcset=\"https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0783-1024x682.jpg 1024w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0783-300x200.jpg 300w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0783-768x512.jpg 768w, https:\/\/www.yangkrok.com\/home\/wp-content\/uploads\/2024\/07\/IMG_0783.jpg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>19 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2567 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e22\u0e32\u0e07\u0e04\u0e23\u0e01 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e25\u0e38\u0e01\u0e08\u0e34\u0e15\u0e2a\u0e33\u0e19\u0e36\u0e01\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e23\u0e30\u0e2b\u0e19\u0e31\u0e01\u0e16\u0e36\u0e07\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e04\u0e39\u0e48\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e17\u0e22 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e38\u0e19\u0e17\u0e23\u0e20\u0e39\u0e48 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2a\u0e35 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e27\u0e32\u0e14\u0e20\u0e32\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2a\u0e35 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e14\u0e04\u0e31\u0e14\u0e25\u0e32\u0e22\u0e21\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e20\u0e32\u0e1e\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e01\u0e25\u0e2d\u0e19 8 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e43\u0e19\u0e27\u0e23\u0e23\u0e13\u0e04\u0e14\u0e35\u0e44\u0e17\u0e22 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e43\u0e19\u0e27\u0e23\u0e23\u0e13\u0e04\u0e14\u0e35\u0e44\u0e17\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e0a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e08\u0e32\u0e01\u0e04\u0e13\u0e30\u0e04\u0e23\u0e39\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e22\u0e32\u0e07\u0e04\u0e23\u0e01 \u0e13 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e22\u0e32\u0e07\u0e04\u0e23\u0e01 \u0e15\u0e33\u0e1a\u0e25\u0e22\u0e32\u0e07\u0e40\u0e1b\u0e35\u0e22\u0e07 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2d\u0e21\u0e01\u0e4b\u0e2d\u0e22 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48<\/p>\n","protected":false},"author":1,"featured_media":1192,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[114,115,113],"class_list":["post-1190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3","tag-114","tag-115","tag-113"],"_links":{"self":[{"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/posts\/1190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/comments?post=1190"}],"version-history":[{"count":2,"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/posts\/1190\/revisions"}],"predecessor-version":[{"id":1215,"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/posts\/1190\/revisions\/1215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/media\/1192"}],"wp:attachment":[{"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/media?parent=1190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/categories?post=1190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yangkrok.com\/home\/wp-json\/wp\/v2\/tags?post=1190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}